{"id":27,"count":443,"description":"","link":"https:\/\/metobrew.com\/zh\/blog\/","name":"\u535a\u5ba2","slug":"blog","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/metobrew.com\/zh\/wp-json\/wp\/v2\/categories\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metobrew.com\/zh\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/metobrew.com\/zh\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/metobrew.com\/zh\/wp-json\/wp\/v2\/posts?categories=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}